{"id":223,"date":"2021-10-01T02:18:59","date_gmt":"2021-10-01T02:18:59","guid":{"rendered":"https:\/\/crewinc.com.au\/irap\/?page_id=223"},"modified":"2022-12-23T04:36:29","modified_gmt":"2022-12-23T04:36:29","slug":"manoeuvring","status":"publish","type":"page","link":"https:\/\/toolkit.irap.org\/fr\/crash-type\/manoeuvring\/","title":{"rendered":"Man\u0153uvrer"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"223\" class=\"elementor elementor-223\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cac0bf elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5cac0bf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33c8c50\" data-id=\"33c8c50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd18d32 elementor-widget elementor-widget-spacer\" data-id=\"fd18d32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20a51dd elementor-widget elementor-widget-image\" data-id=\"20a51dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"677\" height=\"79\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2021\/09\/Rectangle-6612.png\" class=\"attachment-full size-full wp-image-94\" alt=\"\" srcset=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2021\/09\/Rectangle-6612.png 677w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2021\/09\/Rectangle-6612-300x35.png 300w\" sizes=\"(max-width: 677px) 100vw, 677px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad824ee elementor-widget elementor-widget-raven-search-form\" data-id=\"ad824ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_skin&quot;:&quot;classic&quot;}\" data-widget_type=\"raven-search-form.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"raven-search-form raven-search-form-classic\" method=\"get\" action=\"https:\/\/toolkit.irap.org\/fr\/\" role=\"search\" data-trp-original-action=\"https:\/\/toolkit.irap.org\/fr\/\">\n\t\t\t<div class=\"raven-search-form-container\">\n\t\t\t\t<div class=\"raven-search-form-inner\">\n\t\t\t\t\t<label class=\"elementor-screen-only\" for=\"raven-search-form-input\">Recherche<\/label>\n\t\t\t\t\t<input id=\"raven-search-form-input\" class=\"raven-search-form-input\" type=\"search\" name=\"s\" placeholder=\"Chercher...\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"raven-search-form-button raven-search-form-button-svg\" type=\"submit\" aria-label=\"Recherche\">\n\t\t\t\t\t\t\t\t\t<i class=\"fas fa-search\"><\/i>\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18cf729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18cf729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33ccecb\" data-id=\"33ccecb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffa3fba elementor-widget elementor-widget-template\" data-id=\"ffa3fba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"1049\" class=\"elementor elementor-1049\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40dd03b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40dd03b8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-25e071d5\" data-id=\"25e071d5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a505fe9 elementor-widget elementor-widget-image\" data-id=\"a505fe9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/elementor\/thumbs\/bike-pddbssjkumawvux2dcr2ftmtjpfdhyknhink2oyl8g.png\" title=\"Bicyclette\" alt=\"bike\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db0db22 elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"db0db22\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-db0db22\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5139\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Utilisateurs <br \/>de route<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1112\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/pedestrians\/\" class=\"elementor-sub-item\">Pi\u00e9tons<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1109\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/bicyclists-and-light-mobility\/\" class=\"elementor-sub-item\">Cyclistes et mobilit\u00e9 l\u00e9g\u00e8re<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1111\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/motorcyclists\/\" class=\"elementor-sub-item\">Motocyclistes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1463\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/car-occupants\/\" class=\"elementor-sub-item\">Occupants De Voitures<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1113\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/public-transport-vehicles\/\" class=\"elementor-sub-item\">V\u00e9hicules de transport public<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1110\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/heavy-vehicles\/\" class=\"elementor-sub-item\">V\u00e9hicules lourds<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-db0db22\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5139\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Utilisateurs <br \/>de route<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1112\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/pedestrians\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pi\u00e9tons<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1109\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/bicyclists-and-light-mobility\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cyclistes et mobilit\u00e9 l\u00e9g\u00e8re<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1111\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/motorcyclists\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Motocyclistes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1463\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/car-occupants\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Occupants De Voitures<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1113\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/public-transport-vehicles\/\" class=\"elementor-sub-item\" tabindex=\"-1\">V\u00e9hicules de transport public<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1110\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-users\/heavy-vehicles\/\" class=\"elementor-sub-item\" tabindex=\"-1\">V\u00e9hicules lourds<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-141df0ec\" data-id=\"141df0ec\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48776c74 elementor-widget elementor-widget-image\" data-id=\"48776c74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/elementor\/thumbs\/accident-pddbsrlqns9mk8yfiucfvbvcybk0a9gx5e02lezzeo.png\" title=\"accident\" alt=\"accident\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7afb83 elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"b7afb83\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-b7afb83\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5138\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Type d&#039;accident<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1059\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/pedestrian\/\" class=\"elementor-sub-item\">Pi\u00e9ton<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1054\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/bicyclist-and-light-mobility\/\" class=\"elementor-sub-item\">Cycliste et Mobilit\u00e9 L\u00e9g\u00e8re<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1055\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/head-on\/\" class=\"elementor-sub-item\">De front<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1056\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/intersections\/\" class=\"elementor-sub-item\">Intersections<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1104\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/run-off-road\/\" class=\"elementor-sub-item\">Courir hors route<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1060\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/rear-end\/\" class=\"elementor-sub-item\">Extr\u00e9mit\u00e9 arri\u00e8re<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1057\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/lane-change\/\" class=\"elementor-sub-item\">Changement de voie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1058\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/manoeuvring\/\" class=\"elementor-sub-item\">Man\u0153uvrer<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-b7afb83\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5138\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Type d&#039;accident<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1059\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/pedestrian\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pi\u00e9ton<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1054\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/bicyclist-and-light-mobility\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cycliste et Mobilit\u00e9 L\u00e9g\u00e8re<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1055\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/head-on\/\" class=\"elementor-sub-item\" tabindex=\"-1\">De front<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1056\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/intersections\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Intersections<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1104\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/run-off-road\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Courir hors route<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1060\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/rear-end\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Extr\u00e9mit\u00e9 arri\u00e8re<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1057\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/lane-change\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Changement de voie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1058\"><a href=\"https:\/\/toolkit.irap.org\/fr\/crash-type\/manoeuvring\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Man\u0153uvrer<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6eb2ff86\" data-id=\"6eb2ff86\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30b15ea7 elementor-widget elementor-widget-image\" data-id=\"30b15ea7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/elementor\/thumbs\/road-pddbssjkumawvux2dcr2ftmtjpfdhyknhink2oyl8g.png\" title=\"route\" alt=\"road\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11553c1 elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"11553c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-11553c1\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5137\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Types de route<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1089\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-types\/streets\/\" class=\"elementor-sub-item\">Des rues<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1088\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-types\/distributors\/\" class=\"elementor-sub-item\">Distributeurs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1107\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-types\/highways\/\" class=\"elementor-sub-item\">Autoroutes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1108\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-types\/motorways\/\" class=\"elementor-sub-item\">Autoroutes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1090\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-types\/tunnels\/\" class=\"elementor-sub-item\">Tunnels<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-11553c1\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5137\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Types de route<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1089\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-types\/streets\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Des rues<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1088\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-types\/distributors\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Distributeurs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1107\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-types\/highways\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Autoroutes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1108\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-types\/motorways\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Autoroutes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1090\"><a href=\"https:\/\/toolkit.irap.org\/fr\/road-types\/tunnels\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Tunnels<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-29bb8303\" data-id=\"29bb8303\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7887d781 elementor-widget elementor-widget-image\" data-id=\"7887d781\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/elementor\/thumbs\/warning-sign-pddbsthf1gc77gvp7v5p0bea53aqpnodtnb1jyx728.png\" title=\"panneau d&#039;avertissement\" alt=\"warning sign\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4c7e40 elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"f4c7e40\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-f4c7e40\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5134\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Traitements<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"safer-people-treatments-menu menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5141\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">Des personnes plus s\u00fbres<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1699\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/safe-speed\/\" class=\"elementor-sub-item\">Vitesse de s\u00e9curit\u00e9<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1115\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/addressing-alcohol-and-other-drugs\/\" class=\"elementor-sub-item\">Lutter contre l&#039;alcool et les autres drogues<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1116\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/child-safety-initiatives\/\" class=\"elementor-sub-item\">Initiatives pour la s\u00e9curit\u00e9 des enfants<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1117\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/education\/\" class=\"elementor-sub-item\">\u00c9ducation<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1693\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/emergency-response\/\" class=\"elementor-sub-item\">R\u00e9ponse d&#039;urgence<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1694\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/enforcement\/\" class=\"elementor-sub-item\">Mise en vigueur<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1695\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/fatigue-management\/\" class=\"elementor-sub-item\">Gestion de la fatigue<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1696\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/helmets-and-protective-clothing\/\" class=\"elementor-sub-item\">Casques et v\u00eatements de protection<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1697\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/licensing\/\" class=\"elementor-sub-item\">Licence<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1698\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/publicity\/\" class=\"elementor-sub-item\">Publicit\u00e9<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1700\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/seatbelts\/\" class=\"elementor-sub-item\">Ceinture de s\u00e9curit\u00e9<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"safer-road-treatments-menu menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5142\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">Route plus s\u00fbre<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9072\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">Notions<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2038\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/self-explaining-road-ser-concept\/\" class=\"elementor-sub-item\">Concept de route auto-explicatif (SER)<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2037\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/forgiving-roads-concept\/\" class=\"elementor-sub-item\">Concept de routes indulgentes<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9073\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">Intersections<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1713\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersection-delineation\/\" class=\"elementor-sub-item\">Intersection \u2013 D\u00e9limitation<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1124\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersection-grade-separation\/\" class=\"elementor-sub-item\">Intersection \u2013 D\u00e9nivel\u00e9<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1125\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersection-roundabout\/\" class=\"elementor-sub-item\">Intersection \u2013 Rond-point<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1126\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersection-signalise\/\" class=\"elementor-sub-item\">Intersection \u2013 Signalisation<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1127\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersections-turn-lanes-signalised\/\" class=\"elementor-sub-item\">Intersections \u2013 Voies de virage (signalis\u00e9es)<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1128\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersections-turn-lanes-unsignalised\/\" class=\"elementor-sub-item\">Intersections \u2013 Voies de virage (non signal\u00e9es)<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1130\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/median-crossing-upgrade\/\" class=\"elementor-sub-item\">Mise \u00e0 niveau du franchissement m\u00e9dian<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1138\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/railway-crossing\/\" class=\"elementor-sub-item\">Passage \u00e0 niveau<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9074\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">Bloc interm\u00e9diaire<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1122\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/delineation\/\" class=\"elementor-sub-item\">D\u00e9limitation<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1123\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/duplication\/\" class=\"elementor-sub-item\">Reproduction<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1121\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/central-turning-lane-full-length\/\" class=\"elementor-sub-item\">Voie de virage centrale sur toute la longueur<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1120\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/central-hatching-wide-centrelines\/\" class=\"elementor-sub-item\">Hachures centrales \u2013 Lignes m\u00e9dianes larges<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1129\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/lane-widening\/\" class=\"elementor-sub-item\">\u00c9largissement de voie<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1726\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/median\/\" class=\"elementor-sub-item\">M\u00e9dian<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1132\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/one-way-network\/\" class=\"elementor-sub-item\">R\u00e9seau \u00e0 sens unique<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1133\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/parking-improvements\/\" class=\"elementor-sub-item\">Am\u00e9liorations du stationnement<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1141\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/regulate-roadside-commercial-activity\/\" class=\"elementor-sub-item\">R\u00e9glementer l&#039;activit\u00e9 commerciale en bordure de route<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1139\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/realignment-horizontal\/\" class=\"elementor-sub-item\">R\u00e9alignement \u2013 Horizontal<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1140\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/realignment-vertical\/\" class=\"elementor-sub-item\">R\u00e9alignement \u2013 Vertical<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1142\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/restrict-combine-direct-access-points\/\" class=\"elementor-sub-item\">Restreindre\/combiner les points d&#039;acc\u00e8s direct<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1149\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/skid-resistance\/\" class=\"elementor-sub-item\">R\u00e9sistance au d\u00e9rapage<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1119\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/overtaking-lane-and-2-plus-1-road\/\" class=\"elementor-sub-item\">Voie de d\u00e9passement et route 2+1<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1143\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/road-surface-rehabilitation\/\" class=\"elementor-sub-item\">R\u00e9habilitation de la surface de la route<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1146\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/service-road\/\" class=\"elementor-sub-item\">Voie de service<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1148\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/sight-distance-obstruction-removal\/\" class=\"elementor-sub-item\">Distance de vue (\u00e9limination d&#039;obstruction)<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1150\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/street-lighting\/\" class=\"elementor-sub-item\">L&#039;\u00e9clairage des rues<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9075\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">Bords de route<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1134\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/paved-shoulder\/\" class=\"elementor-sub-item\">\u00c9paule pav\u00e9e<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1144\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/roadside-safety-barriers\/\" class=\"elementor-sub-item\">S\u00e9curit\u00e9 routi\u00e8re \u2013 Barri\u00e8res<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2023\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/roadside-safety-hazard-removal\/\" class=\"elementor-sub-item\">S\u00e9curit\u00e9 routi\u00e8re \u2013 \u00c9limination des dangers<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1147\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/sideslope-improvements\/\" class=\"elementor-sub-item\">S\u00e9curit\u00e9 routi\u00e8re \u2013 Am\u00e9liorations des talus<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1145\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/rumble-strips\/\" class=\"elementor-sub-item\">Bandes rugueuses<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9076\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">Usagers vuln\u00e9rables de la route<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2000\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/bicycle-facilities\/\" class=\"elementor-sub-item\">Installations pour v\u00e9los<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1131\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/motorcycle-lanes\/\" class=\"elementor-sub-item\">Voies de moto<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1135\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-crossing-grade-separation\/\" class=\"elementor-sub-item\">Passage pour pi\u00e9tons \u2013 D\u00e9nivel\u00e9<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1136\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-crossing-signalised\/\" class=\"elementor-sub-item\">Passage pour pi\u00e9tons \u2013 Signalis\u00e9<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2009\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-crossing-unsignalised\/\" class=\"elementor-sub-item\">Passage pour pi\u00e9tons \u2013 Non signal\u00e9<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-4226\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-crossing-raised\/\" class=\"elementor-sub-item\">Passage pour pi\u00e9tons \u2013 sur\u00e9lev\u00e9<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2018\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-fencing\/\" class=\"elementor-sub-item\">Cl\u00f4ture pour pi\u00e9tons<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2013\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-footpath\/\" class=\"elementor-sub-item\">Sentier pi\u00e9ton<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1137\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-refuge-island\/\" class=\"elementor-sub-item\">\u00cele du refuge pour pi\u00e9tons<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-4025\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/road-works-safety\/\" class=\"elementor-sub-item\">S\u00e9curit\u00e9 des travaux routiers<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2033\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/school-zones\/\" class=\"elementor-sub-item\">Zones scolaires<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2034\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/speed-management-and-traffic-calming\/\" class=\"elementor-sub-item\">Gestion de la vitesse et apaisement du trafic<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"safer-vehicle-treatments-menu menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5143\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">V\u00e9hicule plus s\u00fbr<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1705\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-vehicle-treatments\/motor-vehicle-standards\/\" class=\"elementor-sub-item\">Normes relatives aux v\u00e9hicules \u00e0 moteur<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1701\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-vehicle-treatments\/new-car-assessment-programs-ncap\/\" class=\"elementor-sub-item\">Programmes d&#039;\u00e9valuation des voitures neuves (NCAP)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1702\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-vehicle-treatments\/safety-features-and-devices\/\" class=\"elementor-sub-item\">Fonctionnalit\u00e9s et dispositifs de s\u00e9curit\u00e9<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1703\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-vehicle-treatments\/used-car-safety-ratings\/\" class=\"elementor-sub-item\">Cotes de s\u00e9curit\u00e9 des voitures d&#039;occasion<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1704\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-vehicle-treatments\/vehicle-roadworthiness\/\" class=\"elementor-sub-item\">Contr\u00f4le technique du v\u00e9hicule<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-f4c7e40\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5134\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Traitements<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"safer-people-treatments-menu menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5141\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">Des personnes plus s\u00fbres<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1699\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/safe-speed\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Vitesse de s\u00e9curit\u00e9<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1115\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/addressing-alcohol-and-other-drugs\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Lutter contre l&#039;alcool et les autres drogues<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1116\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/child-safety-initiatives\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Initiatives pour la s\u00e9curit\u00e9 des enfants<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1117\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/education\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u00c9ducation<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1693\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/emergency-response\/\" class=\"elementor-sub-item\" tabindex=\"-1\">R\u00e9ponse d&#039;urgence<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1694\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/enforcement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Mise en vigueur<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1695\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/fatigue-management\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Gestion de la fatigue<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1696\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/helmets-and-protective-clothing\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Casques et v\u00eatements de protection<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1697\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/licensing\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Licence<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1698\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/publicity\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Publicit\u00e9<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1700\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-people-treatments\/seatbelts\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ceinture de s\u00e9curit\u00e9<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"safer-road-treatments-menu menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5142\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">Route plus s\u00fbre<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9072\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">Notions<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2038\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/self-explaining-road-ser-concept\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Concept de route auto-explicatif (SER)<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2037\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/forgiving-roads-concept\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Concept de routes indulgentes<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9073\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">Intersections<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1713\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersection-delineation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Intersection \u2013 D\u00e9limitation<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1124\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersection-grade-separation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Intersection \u2013 D\u00e9nivel\u00e9<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1125\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersection-roundabout\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Intersection \u2013 Rond-point<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1126\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersection-signalise\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Intersection \u2013 Signalisation<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1127\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersections-turn-lanes-signalised\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Intersections \u2013 Voies de virage (signalis\u00e9es)<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1128\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/intersections-turn-lanes-unsignalised\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Intersections \u2013 Voies de virage (non signal\u00e9es)<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1130\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/median-crossing-upgrade\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Mise \u00e0 niveau du franchissement m\u00e9dian<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1138\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/railway-crossing\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Passage \u00e0 niveau<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9074\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">Bloc interm\u00e9diaire<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1122\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/delineation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">D\u00e9limitation<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1123\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/duplication\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Reproduction<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1121\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/central-turning-lane-full-length\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Voie de virage centrale sur toute la longueur<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1120\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/central-hatching-wide-centrelines\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hachures centrales \u2013 Lignes m\u00e9dianes larges<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1129\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/lane-widening\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u00c9largissement de voie<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1726\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/median\/\" class=\"elementor-sub-item\" tabindex=\"-1\">M\u00e9dian<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1132\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/one-way-network\/\" class=\"elementor-sub-item\" tabindex=\"-1\">R\u00e9seau \u00e0 sens unique<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1133\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/parking-improvements\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Am\u00e9liorations du stationnement<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1141\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/regulate-roadside-commercial-activity\/\" class=\"elementor-sub-item\" tabindex=\"-1\">R\u00e9glementer l&#039;activit\u00e9 commerciale en bordure de route<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1139\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/realignment-horizontal\/\" class=\"elementor-sub-item\" tabindex=\"-1\">R\u00e9alignement \u2013 Horizontal<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1140\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/realignment-vertical\/\" class=\"elementor-sub-item\" tabindex=\"-1\">R\u00e9alignement \u2013 Vertical<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1142\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/restrict-combine-direct-access-points\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Restreindre\/combiner les points d&#039;acc\u00e8s direct<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1149\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/skid-resistance\/\" class=\"elementor-sub-item\" tabindex=\"-1\">R\u00e9sistance au d\u00e9rapage<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1119\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/overtaking-lane-and-2-plus-1-road\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Voie de d\u00e9passement et route 2+1<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1143\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/road-surface-rehabilitation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">R\u00e9habilitation de la surface de la route<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1146\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/service-road\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Voie de service<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1148\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/sight-distance-obstruction-removal\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Distance de vue (\u00e9limination d&#039;obstruction)<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1150\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/street-lighting\/\" class=\"elementor-sub-item\" tabindex=\"-1\">L&#039;\u00e9clairage des rues<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9075\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">Bords de route<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1134\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/paved-shoulder\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u00c9paule pav\u00e9e<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1144\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/roadside-safety-barriers\/\" class=\"elementor-sub-item\" tabindex=\"-1\">S\u00e9curit\u00e9 routi\u00e8re \u2013 Barri\u00e8res<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2023\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/roadside-safety-hazard-removal\/\" class=\"elementor-sub-item\" tabindex=\"-1\">S\u00e9curit\u00e9 routi\u00e8re \u2013 \u00c9limination des dangers<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1147\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/sideslope-improvements\/\" class=\"elementor-sub-item\" tabindex=\"-1\">S\u00e9curit\u00e9 routi\u00e8re \u2013 Am\u00e9liorations des talus<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1145\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/rumble-strips\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bandes rugueuses<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9076\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">Usagers vuln\u00e9rables de la route<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2000\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/bicycle-facilities\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Installations pour v\u00e9los<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1131\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/motorcycle-lanes\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Voies de moto<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1135\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-crossing-grade-separation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Passage pour pi\u00e9tons \u2013 D\u00e9nivel\u00e9<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1136\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-crossing-signalised\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Passage pour pi\u00e9tons \u2013 Signalis\u00e9<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2009\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-crossing-unsignalised\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Passage pour pi\u00e9tons \u2013 Non signal\u00e9<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-4226\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-crossing-raised\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Passage pour pi\u00e9tons \u2013 sur\u00e9lev\u00e9<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2018\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-fencing\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cl\u00f4ture pour pi\u00e9tons<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2013\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-footpath\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Sentier pi\u00e9ton<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-1137\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/pedestrian-refuge-island\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u00cele du refuge pour pi\u00e9tons<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-4025\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/road-works-safety\/\" class=\"elementor-sub-item\" tabindex=\"-1\">S\u00e9curit\u00e9 des travaux routiers<\/a><\/li>\n\t\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2033\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/school-zones\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Zones scolaires<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"safer-road-treatments-l2 menu-item menu-item-type-post_type menu-item-object-page menu-item-2034\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-road-treatments\/speed-management-and-traffic-calming\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Gestion de la vitesse et apaisement du trafic<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"safer-vehicle-treatments-menu menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5143\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">V\u00e9hicule plus s\u00fbr<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1705\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-vehicle-treatments\/motor-vehicle-standards\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Normes relatives aux v\u00e9hicules \u00e0 moteur<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1701\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-vehicle-treatments\/new-car-assessment-programs-ncap\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Programmes d&#039;\u00e9valuation des voitures neuves (NCAP)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1702\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-vehicle-treatments\/safety-features-and-devices\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Fonctionnalit\u00e9s et dispositifs de s\u00e9curit\u00e9<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1703\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-vehicle-treatments\/used-car-safety-ratings\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cotes de s\u00e9curit\u00e9 des voitures d&#039;occasion<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1704\"><a href=\"https:\/\/toolkit.irap.org\/fr\/safer-vehicle-treatments\/vehicle-roadworthiness\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Contr\u00f4le technique du v\u00e9hicule<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-406011c7\" data-id=\"406011c7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b11ea48 elementor-widget elementor-widget-image\" data-id=\"3b11ea48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/elementor\/thumbs\/person-pddbssjkumawvux2dcr2ftmtjpfdhyknhink2oyl8g.png\" title=\"personne\" alt=\"person\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d49bcc7 elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"d49bcc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-d49bcc7\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5136\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Gestion<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1106\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/safe-system-approach\/\" class=\"elementor-sub-item\">Approche du syst\u00e8me s\u00fbr<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2036\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/road-safety-plans\/\" class=\"elementor-sub-item\">Plans de s\u00e9curit\u00e9 routi\u00e8re<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1085\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/goals-targets-and-indicators\/\" class=\"elementor-sub-item\">Objectifs, cibles et indicateurs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1105\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/road-safety-data\/\" class=\"elementor-sub-item\">Donn\u00e9es de s\u00e9curit\u00e9 routi\u00e8re<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1084\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/crash-costing\/\" class=\"elementor-sub-item\">Co\u00fbt de l&#039;accident<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3666\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/multimodal-transport-and-land-use-planning\/\" class=\"elementor-sub-item\">Transport multimodal et am\u00e9nagement du territoire<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1690\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/building-capacity\/\" class=\"elementor-sub-item\">Renforcement des capacit\u00e9s<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3635\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/collaboration\/\" class=\"elementor-sub-item\">Collaboration<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3626\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/stakeholder-engagement\/\" class=\"elementor-sub-item\">Engagement des parties prenantes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1086\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/infrastructure-safety-management-tools\/\" class=\"elementor-sub-item\">Outils de gestion de la s\u00e9curit\u00e9 des infrastructures<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2441\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/reference-materials\/\" class=\"elementor-sub-item\">Mat\u00e9riel de r\u00e9f\u00e9rence<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11605\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/safer-roads-resource-sharing\/\" class=\"elementor-sub-item\">Partage des ressources pour des routes plus s\u00fbres<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-d49bcc7\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5136\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Gestion<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1106\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/safe-system-approach\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Approche du syst\u00e8me s\u00fbr<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2036\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/road-safety-plans\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Plans de s\u00e9curit\u00e9 routi\u00e8re<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1085\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/goals-targets-and-indicators\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Objectifs, cibles et indicateurs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1105\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/road-safety-data\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Donn\u00e9es de s\u00e9curit\u00e9 routi\u00e8re<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1084\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/crash-costing\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Co\u00fbt de l&#039;accident<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3666\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/multimodal-transport-and-land-use-planning\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Transport multimodal et am\u00e9nagement du territoire<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1690\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/building-capacity\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Renforcement des capacit\u00e9s<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3635\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/collaboration\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Collaboration<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3626\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/stakeholder-engagement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Engagement des parties prenantes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1086\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/infrastructure-safety-management-tools\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Outils de gestion de la s\u00e9curit\u00e9 des infrastructures<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2441\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/reference-materials\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Mat\u00e9riel de r\u00e9f\u00e9rence<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11605\"><a href=\"https:\/\/toolkit.irap.org\/fr\/management\/safer-roads-resource-sharing\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Partage des ressources pour des routes plus s\u00fbres<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61088a5 breadcrumbs-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61088a5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6437d3\" data-id=\"b6437d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16fda3b elementor-align-left elementor-widget elementor-widget-raven-breadcrumbs\" data-id=\"16fda3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"raven-breadcrumbs raven-breadcrumbs-default\"><div class=\"breadcrumb\">\t\t\t\t\t\t\t\t<div class=\"breadcrumb-item active\" aria-current=\"page\"><span>Domicile<\/span><\/div>\n\n\t\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7dce8f92 crash-type-content-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7dce8f92\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-77019072\" data-id=\"77019072\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23d11847 elementor-widget elementor-widget-heading\" data-id=\"23d11847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Man\u0153uvrer<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e34bea1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5e34bea1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3efb295d elementor-widget elementor-widget-text-editor\" data-id=\"3efb295d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Diff\u00e9rents types d&#039;accidents peuvent se produire lorsque des v\u00e9hicules man\u0153uvrent. Les man\u0153uvres comprennent les v\u00e9hicules et les motos entrant ou sortant de la chauss\u00e9e, les virages autres qu&#039;aux intersections (y compris les virages en \u00ab U \u00bb) et le stationnement.<\/strong><\/p><p>Les v\u00e9hicules et les motos peuvent entrer ou sortir de la chauss\u00e9e pour un certain nombre de raisons. Il s&#039;agit notamment d&#039;acc\u00e9der \u00e0 une propri\u00e9t\u00e9 en bordure de route (logement ou commerce) ou \u00e0 une autre activit\u00e9 en bordure de route. Cela devient un probl\u00e8me plus important lorsque les v\u00e9hicules et les motos doivent traverser des flux de trafic oppos\u00e9s. L&#039;activit\u00e9 en bord de route comprend les v\u00e9hicules et les motos s&#039;arr\u00eatant sur les march\u00e9s en bordure de route ou \u00e0 des points de d\u00e9p\u00f4t ou de ramassage informels pour pi\u00e9tons. C&#039;est particuli\u00e8rement un probl\u00e8me dans les zones p\u00e9riph\u00e9riques urbaines o\u00f9 la vitesse de circulation est souvent plus \u00e9lev\u00e9e, mais aussi un grand nombre d&#039;usagers vuln\u00e9rables de la route, y compris les pi\u00e9tons.<\/p><p>Des accidents de man\u0153uvre peuvent \u00e9galement se produire lorsque des v\u00e9hicules entrent ou sortent d&#039;une position de stationnement. Cela peut entra\u00eener des collisions avec d&#039;autres v\u00e9hicules ou avec des usagers vuln\u00e9rables de la route, notamment des pi\u00e9tons, des cyclistes et des motocyclistes.<\/p><p>Les collisions en demi-tour peuvent se produire lorsque le v\u00e9hicule qui tourne en U est heurt\u00e9 par un v\u00e9hicule venant de la direction oppos\u00e9e ou par un v\u00e9hicule venant de la m\u00eame direction.<\/p><p>Les facteurs typiques qui peuvent augmenter le risque d&#039;accident lors des man\u0153uvres comprennent\u00a0:<\/p><ul><li class=\"translation-block\"><a href=\"\/fr\/safer-people-treatments\/safe-speed\/\" target=\"_self\">Vitesses<\/a> inappropri\u00e9es.<\/li><li class=\"translation-block\">Absence de <a href=\"\/fr\/safer-road-treatments\/pedestrian-footpath\/\" target=\"_self\">sentiers<\/a> , de <a href=\"\/fr\/safer-road-treatments\/pedestrian-crossing-signalised\/\" target=\"_self\">passages pour pi\u00e9tons<\/a> ou <a href=\"\/fr\/safer-road-treatments\/bicycle-facilities\/\" target=\"_self\">d&#039;installations cyclables<\/a> .<\/li><li class=\"translation-block\"><a href=\"\/fr\/safer-road-treatments\/sight-distance-obstruction-removal\/\" target=\"_self\">Distance de vue<\/a> <a href=\"\/fr\/safer-road-treatments\/bicycle-facilities\/?trp-edit-translation=preview\" target=\"_self\">insuffisante<\/a> .<\/li><li>Manque d&#039;opportunit\u00e9s et d&#039;installations de virage.<\/li><li><a href=\"\/fr\/safer-road-treatments\/regulate-roadside-commercial-activity\/\">Activit\u00e9 en bord de route<\/a> et <a href=\"\/fr\/safer-road-treatments\/parking-improvements\/\">parking mal g\u00e9r\u00e9<\/a>.<\/li><li>Manque de visibilit\u00e9 aux intersections, y compris un manque de <a href=\"\/fr\/safer-road-treatments\/street-lighting\/\">r\u00e9verb\u00e8res<\/a><\/li><li class=\"translation-block\">Mauvaises <a href=\"\/fr\/safer-road-treatments\/median-crossing-upgrade\/\" target=\"_self\">installations de passage m\u00e9dian<\/a> .<\/li><li class=\"translation-block\"><a href=\"\/fr\/safer-people-treatments\/fatigue-management\/\" target=\"_self\">Fatigue<\/a> conducteur\/pilote .<\/li><li class=\"translation-block\"><a href=\"\/fr\/irap\/safer-people-treatments\/addressing-alcohol-and-other-drugs\/\" target=\"_self\">Alcool\/drogues\/m\u00e9dicaments<\/a> affaiblissement.<\/li><li>Distraction, y compris l&#039;inattention due \u00e0 l&#039;utilisation du t\u00e9l\u00e9phone portable.<\/li><li>Manque de <a href=\"\/fr\/safer-vehicle-treatments\/safety-features-and-devices\/\">dispositifs de s\u00e9curit\u00e9 du v\u00e9hicule<\/a>.<\/li><li>Mauvais \u00e9tat du v\u00e9hicule <a href=\"\/fr\/safer-vehicle-treatments\/vehicle-roadworthiness\/\">pneus, phares, freins et feux stop<\/a>.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1a55e86b\" data-id=\"1a55e86b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-626b8cf2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"626b8cf2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-61fd6c8\" data-id=\"61fd6c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e204f84 elementor-widget elementor-widget-shortcode\" data-id=\"e204f84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><table class=\"with_frm_style frm-responsive-table frm-grid formidable-related-tables-all\">\n<thead>\n<tr>\n<th>Derni\u00e8res \u00e9tudes de cas<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style='--v-responsive-table-label:\"Latest case studies\";'><a href=\"https:\/\/www.roadsafetyfacility.org\/publications\/brief-overview-road-safety-approach-singapore\">Un bref aper\u00e7u de l&#039;approche de la s\u00e9curit\u00e9 routi\u00e8re \u00e0 Singapour<\/a><\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Latest case studies\";'><a href=\"https:\/\/toolkit.irap.org\/fr\/case-studies\/case-study-britains-most-improved-road-eurorap-performance-tracking-a404-amersham-england\/\">A404 Amersham<\/a><\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Latest case studies\";'><a href=\"https:\/\/resources.irap.org\/General\/IRAP%20Belize%20Case%20Study.pdf\">Am\u00e9liorations de la s\u00e9curit\u00e9 routi\u00e8re de Belize City \u00e0 Belmopan<\/a><\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Latest case studies\";'><a href=\"https:\/\/www.itf-oecd.org\/sites\/default\/files\/docs\/best-practice-urban-road-safety.pdf\">Meilleures pratiques pour la s\u00e9curit\u00e9 routi\u00e8re urbaine\u00a0: \u00e9tudes de cas<\/a><\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Latest case studies\";'><a href=\"https:\/\/www.roadsafetyfacility.org\/success-stories\/better-data-safer-roads-philippines\">De meilleures donn\u00e9es pour des routes plus s\u00fbres aux Philippines\u00a0: une nouvelle l\u00e9gislation soutenant la mise \u00e0 l&#039;\u00e9chelle nationale de DRIVER aux Philippines<\/a><\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Latest case studies\";'><a href=\"https:\/\/www.grsproadsafety.org\/wp-content\/uploads\/2023\/03\/New-Case-1c-Turkey.pdf\">Cr\u00e9er une dynamique pour les lois sur la ceinture de s\u00e9curit\u00e9 en Turquie<\/a><\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Latest case studies\";'><a href=\"https:\/\/blogs.worldbank.org\/transport\/building-safer-roads-through-better-design-and-better-contracts\">Construire des routes plus s\u00fbres gr\u00e2ce \u00e0 une meilleure conception et de meilleurs contrats<\/a><\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Latest case studies\";'><a href=\"http:\/\/www.bea-tt.equipement.gouv.fr\">Collecte des rapports d&#039;enqu\u00eate sur les accidents graves de la route sur le site du Bureau d&#039;enqu\u00eate sur les accidents des transports de surface<\/a><\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Latest case studies\";'><a href=\"https:\/\/www.fiafoundation.org\/connect\/publications\/head-first-a-case-study-of-vietnam-s-motorcycle-helmet-campaign\">Cr\u00e9ation et mise en \u0153uvre d&#039;un plan pour le port du casque pour les enfants au Vietnam<\/a><\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Latest case studies\";'><a href=\"https:\/\/eurorap.org\/wp-content\/uploads\/2021\/03\/CS-EB_Moldova.pdf\">Sections transversales et mi-bloc Route nationale M2-R7 Jonction Saratenii-Soroca-Drochia<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"frm_pagination_cont\">\n<ul class=\"frm_pagination\">\n<li class=\"active\"><a href=\"\/fr\/wp-json\/wp\/v2\/pages\/223?frm-page-3429=1\">1<\/a><\/li>\n<li class=\"\"><a href=\"\/fr\/wp-json\/wp\/v2\/pages\/223?frm-page-3429=2\">2<\/a><\/li>\n<li class=\"\"><a href=\"\/fr\/wp-json\/wp\/v2\/pages\/223?frm-page-3429=3\">3<\/a><\/li>\n<li class=\"dots disabled\">\u2026<\/li>\n<li class=\"\"><a href=\"\/fr\/wp-json\/wp\/v2\/pages\/223?frm-page-3429=5\">5<\/a><\/li>\n<li class=\"\"><a href=\"\/fr\/wp-json\/wp\/v2\/pages\/223?frm-page-3429=2\" class=\"next\">\u00bb<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77bd9ba elementor-align-center elementor-widget elementor-widget-global elementor-global-7709 elementor-widget-button\" data-id=\"77bd9ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"\/fr\/case-studies\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir toutes les \u00e9tudes de cas <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08a8e12 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-template\" data-id=\"08a8e12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c473c3 crash-type-content-container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c473c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cfae73e\" data-id=\"cfae73e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-991da07 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"991da07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bcb8bb elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"8bcb8bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1461\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1461\" aria-expanded=\"false\">Des routes plus s\u00fbres<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1462\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1462\" aria-expanded=\"false\">Des v\u00e9hicules plus s\u00fbrs<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1463\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1463\" aria-expanded=\"false\">Des personnes plus s\u00fbres<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1461\" aria-expanded=\"false\">Des routes plus s\u00fbres<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1461\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1461\" tabindex=\"0\" hidden=\"false\"><p><table class=\"with_frm_style frm-responsive-table frm-alt-table\">\n<thead>\n<tr>\n<th>Nom<\/th>\n<th>\u00c9valuation des co\u00fbts<\/th>\n<th>Efficacit\u00e9<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/bicycle-facilities\/\">Installations pour v\u00e9los<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Faible \u00e0 moyen<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>25 \u2013 40%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/central-turning-lane-full-length\/\">Voie de virage centrale sur toute la longueur<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Faible<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>10 \u2013 25%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/delineation\/\">D\u00e9limitation<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Faible<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>10 \u2013 25%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/intersections-turn-lanes-signalised\/\">Intersection \u2013 Voies de virage (signal\u00e9es)<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Faible \u00e0 moyen<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>10 \u2013 25%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/intersections-turn-lanes-unsignalised\/\">Intersection \u2013 Voies de virage (non signal\u00e9es)<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Faible \u00e0 moyen<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>10 \u2013 25%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/median-crossing-upgrade\/\">Mise \u00e0 niveau du franchissement m\u00e9dian<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Faible \u00e0 moyen<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>25 \u2013 40%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/one-way-network\/\">R\u00e9seau \u00e0 sens unique<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Moyen<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>25 \u2013 40%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/parking-improvements\/\">Am\u00e9liorations du stationnement<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Faible \u00e0 moyen<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>10 \u2013 25%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/regulate-roadside-commercial-activity\/\">R\u00e9glementer l&#039;activit\u00e9 commerciale en bordure de route<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Faible \u00e0 moyen<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>10 \u2013 25%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/restrict-combine-direct-access-points\/\">Restreindre\/combiner les points d&#039;acc\u00e8s direct<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Moyen \u00e0 \u00e9lev\u00e9<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>25 \u2013 40%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/service-road\/\">Voie de service<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Haut<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>25 \u2013 40%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/speed-management-and-traffic-calming\/\">Gestion de la vitesse<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Moyen<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>25 \u2013 40%<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-road-treatments\/speed-management-and-traffic-calming\/\">Apaisement de la circulation<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>Moyen \u00e0 \u00e9lev\u00e9<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>25 \u2013 40%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1462\" aria-expanded=\"false\">Des v\u00e9hicules plus s\u00fbrs<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1462\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1462\" tabindex=\"0\" hidden=\"hidden\"><p><table class=\"with_frm_style frm-responsive-table frm-alt-table\">\n<thead>\n<tr>\n<th>Nom<\/th>\n<th>\u00c9valuation des co\u00fbts<\/th>\n<th>Efficacit\u00e9<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-vehicle-treatments\/motor-vehicle-standards\/\">Normes relatives aux v\u00e9hicules \u00e0 moteur<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-vehicle-treatments\/new-car-assessment-programs-ncap\/\">Programme d&#039;\u00e9valuation des voitures neuves (NCAP)<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-vehicle-treatments\/used-car-safety-ratings\/\">Cotes de s\u00e9curit\u00e9 des voitures d&#039;occasion<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-vehicle-treatments\/safety-features-and-devices\/\">Fonctionnalit\u00e9s et dispositifs de s\u00e9curit\u00e9<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/safer-vehicle-treatments\/vehicle-roadworthiness\/\">Contr\u00f4le technique du v\u00e9hicule<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1463\" aria-expanded=\"false\">Des personnes plus s\u00fbres<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1463\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1463\" tabindex=\"0\" hidden=\"hidden\"><p><table class=\"with_frm_style frm-responsive-table frm-alt-table\">\n<thead>\n<tr>\n<th>Nom<\/th>\n<th>\u00c9valuation des co\u00fbts<\/th>\n<th>Efficacit\u00e9<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-people-treatments\/addressing-alcohol-and-other-drugs\/\">Lutter contre l&#039;alcool et les autres drogues<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-people-treatments\/education\/\">\u00c9ducation<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-people-treatments\/enforcement\/\">Mise en vigueur<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-people-treatments\/fatigue-management\/\">Gestion de la fatigue<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-people-treatments\/helmets-and-protective-clothing\/\">Casques et v\u00eatements de protection<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-people-treatments\/licensing\/\">Licence<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-people-treatments\/publicity\/\">Publicit\u00e9<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-people-treatments\/safe-speed\/\">Vitesse de s\u00e9curit\u00e9<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<tr>\n<td style='--v-responsive-table-label:\"Name\";'><a href=\"#\"><a href=\"\/fr\/irap\/safer-people-treatments\/seatbelts\/\">Ceinture de s\u00e9curit\u00e9<\/a><\/a><\/td>\n<td style='--v-responsive-table-label:\"Cost rating\";'>\u2013<\/td>\n<td style='--v-responsive-table-label:\"Effectiveness\";'>\u2013<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4826bd4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4826bd4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-94c83a2\" data-id=\"94c83a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8201d4b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8201d4b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4f598eb\" data-id=\"4f598eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29c377c elementor-widget elementor-widget-heading\" data-id=\"29c377c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Images connexes<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa878b9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"aa878b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-765cad7 elementor-align-right elementor-widget elementor-widget-global elementor-global-8482 elementor-widget-button\" data-id=\"765cad7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/irap.kontainer.com\/shared\/ffThs62EzfR5z2CnXmNq7hMZt6nc8s3a\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-search\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir toutes les images li\u00e9es au type de crash ici<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86c1700 elementor-widget elementor-widget-shortcode\" data-id=\"86c1700\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"metaslider-id-6490\" style=\"width: 100%; margin: 0 auto;\" class=\"ml-slider-3-108-0 metaslider metaslider-flex metaslider-6490 ml-slider has-dots-nav has-carousel-mode ms-theme-default\" role=\"region\" aria-label=\"1. Type d&#039;accident \u2013 Man\u0153uvre\" data-height=\"300\" data-width=\"370\">\n    <div id=\"metaslider_container_6490\">\n        <div id=\"metaslider_6490\">\n            <ul class='slides'>\n                <li style=\"display: none; width: 100%;\" class=\"slide-6510 ms-image\" aria-roledescription=\"slide\" data-date=\"2022-02-01 01:53:14\" data-filename=\"A-crash-between-two-cars-manoeuvring-iStock-518276611.jpg\" data-slide-type=\"image\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/A-crash-between-two-cars-manoeuvring-iStock-518276611.jpg\" class=\"slider-6490 slide-6510 msDefaultImage\" alt=\"\" rel=\"\" title=\"Accident de voiture\" srcset=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/A-crash-between-two-cars-manoeuvring-iStock-518276611.jpg 600w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/A-crash-between-two-cars-manoeuvring-iStock-518276611-300x200.jpg 300w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/A-crash-between-two-cars-manoeuvring-iStock-518276611-18x12.jpg 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"caption-wrap\"><div class=\"caption\">Un accident entre deux voitures en man\u0153uvre. Cr\u00e9dit photo : iStock<\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-6511 ms-image\" aria-roledescription=\"slide\" data-date=\"2022-02-01 01:53:14\" data-filename=\"A-crash-between-two-cars-manoeuvring-iStock-1317436383.jpg\" data-slide-type=\"image\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/A-crash-between-two-cars-manoeuvring-iStock-1317436383.jpg\" class=\"slider-6490 slide-6511 msDefaultImage\" alt=\"\" rel=\"\" title=\"Accident de voiture \u00e0 Hong Kong\" srcset=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/A-crash-between-two-cars-manoeuvring-iStock-1317436383.jpg 600w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/A-crash-between-two-cars-manoeuvring-iStock-1317436383-300x200.jpg 300w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/A-crash-between-two-cars-manoeuvring-iStock-1317436383-18x12.jpg 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"caption-wrap\"><div class=\"caption\">Un accident entre deux voitures en man\u0153uvre. Cr\u00e9dit photo : iStock<\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-6507 ms-image\" aria-roledescription=\"slide\" data-date=\"2022-02-01 01:53:14\" data-filename=\"IRAP.3999.Infographics_04a.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"543\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/IRAP.3999.Infographics_04a.jpg\" class=\"slider-6490 slide-6507 msDefaultImage\" alt=\"\" rel=\"\" title=\"IRAP.3999.Infographics_04a\" srcset=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/IRAP.3999.Infographics_04a.jpg 600w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/IRAP.3999.Infographics_04a-300x272.jpg 300w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/IRAP.3999.Infographics_04a-13x12.jpg 13w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"caption-wrap\"><div class=\"caption\">Classement par \u00e9toiles des motocyclistes par type d&#039;usager de la route sur la base d&#039;un \u00e9chantillon de 358\u00a0000\u00a0km de routes dans 54\u00a0pays. Cr\u00e9dit image : iRAP<\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-6506 ms-image\" aria-roledescription=\"slide\" data-date=\"2022-02-01 01:53:14\" data-filename=\"IRAP.3999.Infographics_02a.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"543\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/IRAP.3999.Infographics_02a.jpg\" class=\"slider-6490 slide-6506 msDefaultImage\" alt=\"\" rel=\"\" title=\"IRAP.3999.Infographics_02a\" srcset=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/IRAP.3999.Infographics_02a.jpg 600w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/IRAP.3999.Infographics_02a-300x272.jpg 300w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/IRAP.3999.Infographics_02a-13x12.jpg 13w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"caption-wrap\"><div class=\"caption\">Classement par \u00e9toile des occupants du v\u00e9hicule par type d&#039;usager de la route sur la base d&#039;un \u00e9chantillon de 358\u00a0000\u00a0km de routes dans 54\u00a0pays. Cr\u00e9dit image : iRAP<\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-6508 ms-image\" aria-roledescription=\"slide\" data-date=\"2022-02-01 01:53:14\" data-filename=\"Leaving-Parking-graphic.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/Leaving-Parking-graphic.jpg\" class=\"slider-6490 slide-6508 msDefaultImage\" alt=\"\" rel=\"\" title=\"Graphique de sortie de stationnement\" srcset=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/Leaving-Parking-graphic.jpg 600w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/Leaving-Parking-graphic-300x169.jpg 300w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/Leaving-Parking-graphic-18x10.jpg 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"caption-wrap\"><div class=\"caption\">Graphique de sortie de stationnement<\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-6509 ms-image\" aria-roledescription=\"slide\" data-date=\"2022-02-01 01:53:14\" data-filename=\"U-Turn-graphic.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"351\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/U-Turn-graphic.jpg\" class=\"slider-6490 slide-6509 msDefaultImage\" alt=\"\" rel=\"\" title=\"Graphique U Turn\" srcset=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/U-Turn-graphic.jpg 600w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/U-Turn-graphic-300x176.jpg 300w, https:\/\/toolkit.irap.org\/wp-content\/uploads\/2022\/02\/U-Turn-graphic-18x12.jpg 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"caption-wrap\"><div class=\"caption\">Graphique demi-tour<\/div><\/div><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b573bc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6b573bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-695e584\" data-id=\"695e584\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2fcf34 elementor-widget elementor-widget-template\" data-id=\"a2fcf34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"3241\" class=\"elementor elementor-3241\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de665b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de665b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3cdc3f6\" data-id=\"3cdc3f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d77c0e6 elementor-widget elementor-widget-template\" data-id=\"d77c0e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"3056\" class=\"elementor elementor-3056\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1846f246 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1846f246\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71a5bfd6\" data-id=\"71a5bfd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-810a7b2 elementor-arrows-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"810a7b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image \u0915\u0948\u0930\u094b\u0938\u0947\u0932\" dir=\"ltr\" data-no-translation-aria-label=\"\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 \u0915\u093e 1\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2023\/10\/NTRO-ARRB-logo-scaled.jpg\" alt=\"NTRO-ARRB logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 \u0915\u093e 2\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2021\/09\/FIAF.jpg\" alt=\"FIAF\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 \u0915\u093e 3\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2021\/09\/GRSF.jpg\" alt=\"GRSF\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 \u0915\u093e 4\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2021\/11\/world-bank-group-logo.png\" alt=\"world-bank-group-logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 \u0915\u093e 5\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2021\/10\/bloomberg-philanthropies.png\" alt=\"bloomberg-philanthropies\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 \u0915\u093e 6\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2021\/09\/GTKP.jpg\" alt=\"GTKP\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 \u0915\u093e 7\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2021\/09\/IRAP.jpg\" alt=\"IRAP\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 \u0915\u093e 8\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/toolkit.irap.org\/wp-content\/uploads\/2021\/09\/UK.jpg\" alt=\"UK\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Manoeuvring A variety of different crash types can occur when vehicles are manoeuvring. Manoeuvring includes vehicles and motorcycles entering or leaving the roadway, making turns other than at intersections (including \u2018U&#8217; turns) and parking. Vehicles and motorcycles can enter or leave the roadway for a number of reasons. These include to gain access to a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":184,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-223","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/toolkit.irap.org\/fr\/wp-json\/wp\/v2\/pages\/223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toolkit.irap.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/toolkit.irap.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/toolkit.irap.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/toolkit.irap.org\/fr\/wp-json\/wp\/v2\/comments?post=223"}],"version-history":[{"count":70,"href":"https:\/\/toolkit.irap.org\/fr\/wp-json\/wp\/v2\/pages\/223\/revisions"}],"predecessor-version":[{"id":10882,"href":"https:\/\/toolkit.irap.org\/fr\/wp-json\/wp\/v2\/pages\/223\/revisions\/10882"}],"up":[{"embeddable":true,"href":"https:\/\/toolkit.irap.org\/fr\/wp-json\/wp\/v2\/pages\/184"}],"wp:attachment":[{"href":"https:\/\/toolkit.irap.org\/fr\/wp-json\/wp\/v2\/media?parent=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}